{"id":639,"date":"2023-07-06T11:45:56","date_gmt":"2023-07-06T14:45:56","guid":{"rendered":"https:\/\/mrcla.com.br\/?p=639"},"modified":"2023-07-06T16:50:55","modified_gmt":"2023-07-06T19:50:55","slug":"euro-6","status":"publish","type":"post","link":"https:\/\/mrcla.com.br\/en\/legislacao-ferroviaria\/euro-6\/","title":{"rendered":"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">O<\/span> <a href=\"https:\/\/mrcla.com.br\/en\/servicos\/mrcla\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">transporte rodovi\u00e1rio<\/span><\/a><span style=\"font-weight: 400;\"> precisa conviver com a legisla\u00e7\u00e3o ambiental. Uma mudan\u00e7a recente no setor foi o Euro 6. Voc\u00ea est\u00e1 preparado para se adaptar \u00e0s novas regras para motores a diesel?<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nesse sistema, caminh\u00f5es e \u00f4nibus precisam adotar tecnologias que minimizem a emiss\u00e3o de gases poluentes. Por isso, \u00e9 importante conhecer as mudan\u00e7as e seus impactos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Continue a leitura para conhecer o <\/span><b>sistema Euro 6<\/b><span style=\"font-weight: 400;\"> e a sua import\u00e2ncia para o meio ambiente!<\/span><\/p>\n<h2><b>O que \u00e9 o sistema Euro 6<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Euro 6 \u00e9 um protocolo de redu\u00e7\u00e3o de gases poluentes de motores a diesel. Nele, os caminh\u00f5es e \u00f4nibus s\u00e3o obrigados a usar tecnologias para reduzir o hidrocarboneto e o \u00f3xido de nitrog\u00eanio, entre outros gases do efeito estufa, produzidos pela queima de combust\u00edvel.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">No Brasil, a implanta\u00e7\u00e3o do Euro 6 ocorre pela<\/span> <a href=\"http:\/\/conama.mma.gov.br\/?option=com_sisconama&amp;task=arquivo.download&amp;id=767\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">Resolu\u00e7\u00e3o n\u00ba 920 do Conama<\/span><\/a><span style=\"font-weight: 400;\">, chamado de Programa de controle de emiss\u00f5es veiculares (PROCONVE). Por isso, as fabricantes de ve\u00edculos s\u00e3o obrigadas a aplicar o protocolo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Cada fase do programa tem um n\u00famero, ficando cada vez mais rigoroso com o tempo. Atualmente, estamos no Proconve P8, v\u00e1lido desde <\/span><b>1\u00ba de janeiro de 2023.<\/b><\/p>\n<h2><b>Qual sua import\u00e2ncia?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">O sistema Euro 6 faz parte do Acordo de Paris para controle de gases poluentes. Por isso, impacta diretamente o Brasil no com\u00e9rcio exterior, assim como busca minimizar os efeitos para o meio ambiente.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Essa proposta tamb\u00e9m tem o objetivo de promover a moderniza\u00e7\u00e3o da tecnologia utilizada nos motores e combust\u00edveis. Isso porque, obriga a implanta\u00e7\u00e3o de sistemas para minimizar os poluentes.<\/span><\/p>\n<h2><b>Quais s\u00e3o as mudan\u00e7as que ocorrem com esse sistema?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Em rela\u00e7\u00e3o ao protocolo anterior (Proconve P7), as normas para ve\u00edculos pesados sofreram diversas altera\u00e7\u00f5es, que ter\u00e3o impacto direto nos custos da<\/span> <a href=\"https:\/\/mrcla.com.br\/en\/gestao\/supply-chain\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">supply chain<\/span><\/a><span style=\"font-weight: 400;\"> brasileira.\u00a0<\/span><\/p>\n<h3><b>Aplica\u00e7\u00e3o da resolu\u00e7\u00e3o<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">As regras s\u00e3o aplic\u00e1veis a todos os<\/span><b> ve\u00edculos novos<\/b><span style=\"font-weight: 400;\">, a partir de 1\u00ba de janeiro de 2023.<\/span><\/p>\n<h3><b>Objetivo<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">O foco \u00e9 minimizar poluentes:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">\u00d3xidos de nitrog\u00eanio (NOx);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hidrocarbonetos (HC);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Mon\u00f3xido de carbono (CO);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Metano (CH4);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Hidrocarbonetos n\u00e3o met\u00e2nicos (NMHC);<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Am\u00f4nia (NH3).<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">O programa atual tamb\u00e9m exige a redu\u00e7\u00e3o de <\/span><b>ru\u00eddo<\/b><span style=\"font-weight: 400;\">, <\/span><b>n\u00famero de part\u00edculas<\/b><span style=\"font-weight: 400;\">, <\/span><b>material particulado (MP)<\/b><span style=\"font-weight: 400;\"> e <\/span><b>opacidade<\/b><span style=\"font-weight: 400;\"> dos gases emitidos pelo ve\u00edculo.<\/span><\/p>\n<h3><b>Medi\u00e7\u00e3o de poluentes<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Os fabricantes de motores s\u00e3o obrigados a realizar a medi\u00e7\u00e3o por amostragem da emiss\u00e3o de poluentes. Tamb\u00e9m \u00e9 preciso garantir que os motores fiquem dentro dos padr\u00f5es conforme os quil\u00f4metros rodados ou tempo:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">6 anos ou 300.000 km \u2014 ve\u00edculos de carga acima de 3,856 toneladas at\u00e9 16 toneladas;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">7 anos ou 700.000 km \u2014 ve\u00edculos de carga acima de 16 toneladas.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">A tend\u00eancia \u00e9 de mudan\u00e7as na tecnologia utilizada nos ve\u00edculos. O que, como efeito imediato, pode impactar os custos das transportadoras no momento de renovar a frota de caminh\u00f5es.<\/span><\/p>\n<h3><b>Principais tecnologias do Euro 6<\/b><\/h3>\n<p><span style=\"font-weight: 400;\">Algumas tecnologias j\u00e1 s\u00e3o utilizadas para atender aos crit\u00e9rios do sistema Euro 6. Por isso, com os limites previstos no Proconve P8, \u00e9 importante que sejam conhecidas:<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">SCR \u2014 Redu\u00e7\u00e3o Catal\u00edtica Seletiva;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">EGR \u2014 Recircula\u00e7\u00e3o de Gases da Exaust\u00e3o;<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">S-10 \u2014 Uso de diesel com teor reduzido de enxofre.<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">O SCR (Redu\u00e7\u00e3o Catal\u00edtica Seletiva) \u00e9 uma tecnologia que utiliza um catalisador e um agente redutor l\u00edquido (Arla 32). Ap\u00f3s a aplica\u00e7\u00e3o, os gases de escapamento s\u00e3o convertidos em nitrog\u00eanio e vapor de \u00e1gua, que s\u00e3o menos poluentes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">J\u00e1 EGR (Recircula\u00e7\u00e3o de Gases da Exaust\u00e3o) \u00e9 uma tecnologia que recircula parte dos gases de escapamento para a c\u00e2mara de combust\u00e3o, al\u00e9m de promover mudan\u00e7as de temperatura. Com isso, \u00e9 poss\u00edvel inibir a forma\u00e7\u00e3o do NOx.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Por fim, o S-10 \u00e9 um tipo de \u00f3leo diesel com baixo teor de enxofre (m\u00e1ximo de 10 mg\/kg ou ppm). \u00c9 o \u00fanico que atende aos padr\u00f5es da fase P7 do Proconve e permanece homologado para a etapa P8. Al\u00e9m disso, existe a possibilidade de uso do biodiesel.<\/span><\/p>\n<h2><b>Quais s\u00e3o os benef\u00edcios da nova regulamenta\u00e7\u00e3o?<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Os benef\u00edcios do Euro 6 est\u00e3o relacionados \u00e0 sustentabilidade. Tamb\u00e9m \u00e9 poss\u00edvel que haja um fortalecimento da imagem das transportadoras, assim como o desenvolvimento tecnol\u00f3gico dos ve\u00edculos de carga.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Um avan\u00e7o relevante \u00e9 o uso de <\/span><b>motores el\u00e9tricos<\/b><span style=\"font-weight: 400;\">. Como n\u00e3o realizam a queima de combust\u00edvel nem emitem ru\u00eddos, os caminh\u00f5es com essa tecnologia saem na frente em rela\u00e7\u00e3o ao cumprimento da legisla\u00e7\u00e3o ambiental.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Outra solu\u00e7\u00e3o interessante, nesse sentido, \u00e9 a<\/span>\u00a0<a href=\"https:\/\/mrcla.com.br\/en\/servicos\/locacao-de-caminhao\/\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">loca\u00e7\u00e3o de caminh\u00f5es<\/span><\/a><span style=\"font-weight: 400;\">. Assim, as empresas podem ter acesso \u00e0s novas tecnologias com despesas distribu\u00eddas ao longo do tempo \u00e0 medida que geram receita com os ve\u00edculos.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sendo assim, diante das mudan\u00e7as do Euro 6 e do Proconve P8, quem realiza o transporte de cargas e atua com log\u00edstica deve ficar atento \u00e0s novas tecnologias. Procure parceiros no segmento que possam contribuir com a adapta\u00e7\u00e3o \u00e0s normas, ajudando o neg\u00f3cio a lidar com os custos da renova\u00e7\u00e3o de frotas e ter mais lucratividade.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ent\u00e3o, o que voc\u00ea achou das mudan\u00e7as? <\/span><b>Fa\u00e7a um coment\u00e1rio e<\/b> <b>compartilhe um pouco da sua experi\u00eancia com as novas regras<\/b><span style=\"font-weight: 400;\">!<\/span><\/p>","protected":false},"excerpt":{"rendered":"<p>O transporte rodovi\u00e1rio precisa conviver com a legisla\u00e7\u00e3o ambiental. Uma mudan\u00e7a recente no setor foi o Euro 6. Voc\u00ea est\u00e1 preparado para&#8230;<\/p>","protected":false},"author":2,"featured_media":640,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11],"tags":[],"class_list":["post-639","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislacao-ferroviaria"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!<\/title>\n<meta name=\"description\" content=\"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/mrcla.com.br\/en\/legislacao-ferroviaria\/euro-6\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!\" \/>\n<meta property=\"og:description\" content=\"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/mrcla.com.br\/en\/legislacao-ferroviaria\/euro-6\/\" \/>\n<meta property=\"og:site_name\" content=\"MRCLA\" \/>\n<meta property=\"article:published_time\" content=\"2023-07-06T14:45:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-06T19:50:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"mrcla_editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"mrcla_editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/\"},\"author\":{\"name\":\"mrcla_editor\",\"@id\":\"http:\\\/\\\/mrcla.com.br\\\/#\\\/schema\\\/person\\\/1ef2df23d98be8f445c7d47421f6006b\"},\"headline\":\"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!\",\"datePublished\":\"2023-07-06T14:45:56+00:00\",\"dateModified\":\"2023-07-06T19:50:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/\"},\"wordCount\":887,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrcla.com.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/euro-6.jpg\",\"articleSection\":[\"Legisla\u00e7\u00e3o ferrovi\u00e1ria\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/\",\"url\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/\",\"name\":\"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/mrcla.com.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/mrcla.com.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/euro-6.jpg\",\"datePublished\":\"2023-07-06T14:45:56+00:00\",\"dateModified\":\"2023-07-06T19:50:55+00:00\",\"author\":{\"@id\":\"http:\\\/\\\/mrcla.com.br\\\/#\\\/schema\\\/person\\\/1ef2df23d98be8f445c7d47421f6006b\"},\"description\":\"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.\",\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/mrcla.com.br\\\/legislacao-ferroviaria\\\/euro-6\\\/#primaryimage\",\"url\":\"https:\\\/\\\/mrcla.com.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/euro-6.jpg\",\"contentUrl\":\"https:\\\/\\\/mrcla.com.br\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/euro-6.jpg\",\"width\":1080,\"height\":720,\"caption\":\"Sistema euro-6\"},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/mrcla.com.br\\\/#website\",\"url\":\"http:\\\/\\\/mrcla.com.br\\\/\",\"name\":\"MRCLA\",\"description\":\"MITSUI Rail Capital\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/mrcla.com.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"http:\\\/\\\/mrcla.com.br\\\/#\\\/schema\\\/person\\\/1ef2df23d98be8f445c7d47421f6006b\",\"name\":\"mrcla_editor\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g\",\"caption\":\"mrcla_editor\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!","description":"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/mrcla.com.br\/en\/legislacao-ferroviaria\/euro-6\/","og_locale":"en_US","og_type":"article","og_title":"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!","og_description":"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.","og_url":"https:\/\/mrcla.com.br\/en\/legislacao-ferroviaria\/euro-6\/","og_site_name":"MRCLA","article_published_time":"2023-07-06T14:45:56+00:00","article_modified_time":"2023-07-06T19:50:55+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg","type":"image\/jpeg"}],"author":"mrcla_editor","twitter_card":"summary_large_image","twitter_misc":{"Written by":"mrcla_editor","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#article","isPartOf":{"@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/"},"author":{"name":"mrcla_editor","@id":"http:\/\/mrcla.com.br\/#\/schema\/person\/1ef2df23d98be8f445c7d47421f6006b"},"headline":"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!","datePublished":"2023-07-06T14:45:56+00:00","dateModified":"2023-07-06T19:50:55+00:00","mainEntityOfPage":{"@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/"},"wordCount":887,"commentCount":0,"image":{"@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#primaryimage"},"thumbnailUrl":"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg","articleSection":["Legisla\u00e7\u00e3o ferrovi\u00e1ria"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/","url":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/","name":"Sistema Euro 6: o que \u00e9 e quais suas principais mudan\u00e7as? Confira!","isPartOf":{"@id":"http:\/\/mrcla.com.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#primaryimage"},"image":{"@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#primaryimage"},"thumbnailUrl":"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg","datePublished":"2023-07-06T14:45:56+00:00","dateModified":"2023-07-06T19:50:55+00:00","author":{"@id":"http:\/\/mrcla.com.br\/#\/schema\/person\/1ef2df23d98be8f445c7d47421f6006b"},"description":"O sistema Euro 6 foi implementado no Brasil pelo PROCONVE P8, mudando os limites de emiss\u00e3o de poluentes de ve\u00edculos novos a partir de Janeiro de 2023.","inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/mrcla.com.br\/legislacao-ferroviaria\/euro-6\/#primaryimage","url":"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg","contentUrl":"https:\/\/mrcla.com.br\/wp-content\/uploads\/2023\/07\/euro-6.jpg","width":1080,"height":720,"caption":"Sistema euro-6"},{"@type":"WebSite","@id":"http:\/\/mrcla.com.br\/#website","url":"http:\/\/mrcla.com.br\/","name":"MRCLA","description":"MITSUI Rail Capital","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/mrcla.com.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"http:\/\/mrcla.com.br\/#\/schema\/person\/1ef2df23d98be8f445c7d47421f6006b","name":"mrcla_editor","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5c564fd04da5e02cddbaf39d934bc91395bfb37b2c3d14128305d0aea847e9e9?s=96&d=mm&r=g","caption":"mrcla_editor"}}]}},"_links":{"self":[{"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/posts\/639","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/comments?post=639"}],"version-history":[{"count":1,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/posts\/639\/revisions"}],"predecessor-version":[{"id":641,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/posts\/639\/revisions\/641"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/media\/640"}],"wp:attachment":[{"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/media?parent=639"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/categories?post=639"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mrcla.com.br\/en\/wp-json\/wp\/v2\/tags?post=639"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}